{"id":98,"date":"2024-03-27T18:48:39","date_gmt":"2024-03-27T21:48:39","guid":{"rendered":"https:\/\/emisoracolon.com.ar\/?p=98"},"modified":"2024-03-27T18:48:39","modified_gmt":"2024-03-27T21:48:39","slug":"cuantos-alquileres-paga-la-municipalidad","status":"publish","type":"post","link":"https:\/\/emisoracolon.com.ar\/index.php\/2024\/03\/27\/cuantos-alquileres-paga-la-municipalidad\/","title":{"rendered":"\u00bfCu\u00e1ntos alquileres paga la Municipalidad?"},"content":{"rendered":"\n<p>El radicalismo quiere saber la cantidad y monto de alquileres que paga el Municipio.<\/p>\n\n\n\n<p>Milagros Morales dijo \u201c hace un tiempo que tenemos esta inquietud porque, no solo nos referimos a las dependencias municipales que sufren una erogaci\u00f3n de dinero cada vez que llega a fin de mes y hay que pagar las locaciones, sino que tambi\u00e9n el pago de alquileres en concepto de vivienda, \u201cque nos dar\u00e1 una idea de las necesidades habitacionales, y tambi\u00e9n los recursos que destina el Municipio\u201d.<\/p>\n\n\n\n<p>Gonzalo Villalonga del oficialismo respondi\u00f3 que dar\u00e1n a conocer la identidad de las familias que reciben ayuda. \u201cSi estamos de acuerdo con brindar la informaci\u00f3n de monto y cantidad\u201d. Sobre el monto que eroga el Municipio para alquilar locales para cumplir con diversas funciones, sostuvo que todos los contratos pasan por el Concejo Deliberante.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El radicalismo quiere saber la cantidad y monto de alquileres que paga el Municipio. Milagros Morales dijo \u201c hace un tiempo que tenemos esta inquietud porque, no solo nos referimos a las&#8230;<\/p>\n","protected":false},"author":2,"featured_media":99,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-98","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica_local"],"_links":{"self":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=98"}],"version-history":[{"count":1,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/98\/revisions"}],"predecessor-version":[{"id":100,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/98\/revisions\/100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media\/99"}],"wp:attachment":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=98"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=98"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}