{"id":2881,"date":"2024-07-30T18:20:07","date_gmt":"2024-07-30T21:20:07","guid":{"rendered":"https:\/\/emisoracolon.com.ar\/?p=2881"},"modified":"2024-07-30T18:20:07","modified_gmt":"2024-07-30T21:20:07","slug":"comenzaron-las-semifinales-de-inferiores","status":"publish","type":"post","link":"https:\/\/emisoracolon.com.ar\/index.php\/2024\/07\/30\/comenzaron-las-semifinales-de-inferiores\/","title":{"rendered":"Comenzaron las semifinales de inferiores"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El domingo se jugaron los partidos de ida de las semifinales del torneo oficial de divisiones inferiores. Se disputaron en cancha de Porte\u00f1o y Barracas, respectivamente. Los resultados fueron los siguientes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sub\/11<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porte\u00f1o 0 Racing 2 (Francisco Rius y Juan Acastello)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Barracas 1 (Kevin Calvigioni) El Fort\u00edn 3 (Lucio Guerrero, Sim\u00f3n Farr\u00e9 y Emilio Pissinis)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sub\/12<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Fort\u00edn 4 (Amadeo Parodi, Lorenzo Spagnuolo y Tom\u00e1s Molina -2-) 9 de Julio 1 (I\u00e1n Rol\u00f3n)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porte\u00f1o 0 Racing 0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sub\/13 &#8211;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9 de Julio 0 El Fort\u00edn 7 (Jerem\u00edas Talavera, Ger\u00f3nimo Bertoldo -3- Juan Barreto -2- y Mateo Far\u00e9)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Barracas 2 (Bautista Chirino y Rom\u00e1n Duarte) Racing 2 (I\u00e1n Vargas y Sim\u00f3n Cases)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sub\/15<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Racing 1 (Mart\u00edn Motte) El Fort\u00edn 3 (Genardo Salinas y Valent\u00edn Ulla -2-)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porte\u00f1o 3 (Ayrton Iba\u00f1ez, Tiziano Rearte y Rom\u00e1n Britos) Barracas 1 (Facundo Civitillo)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sub\/17 &#8211;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9 de Julio 5 (Genaro D\u00edaz, Diego Gonz\u00e1lez, Dylan Rol\u00f3n -2- Dante Nu\u00f1ez) El Fort\u00edn 1 (Maximiliano Arias)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Barracas 1 (Valentino D\u00edaz) Racing 1 (Jer\u00f3nimo Rey)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada se disput\u00f3 el domingo porque el s\u00e1bado no hab\u00eda \u00e1rbitros en cantidad suficiente, debido a que una terna local debi\u00f3 dirigir en Salto por el Tres Ligas. Las revanchas se juegan el s\u00e1bado venidero en la Mitre, local El Fort\u00edn, y en cancha de Racing.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cancha de Racing<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sub\/11 Racing vs Porte\u00f1o, Sub\/12 Racing vs Porte\u00f1o, Sub\/13 Racing vs Barracas, Sub\/15 Porte\u00f1o vs Barracas y Sub\/17 Racing vs Barracas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cancha Mitre, (local El Fort\u00edn)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sub\/11 El Fort\u00edn vs Barracas, Sub\/12 El Fort\u00edn vs 9 de Julio, Sub\/13 El Fort\u00edn vs 9 de Julio, Sub\/15 El Fort\u00edn vs Racing y Sub\/17 El Fort\u00edn vs 9 de Julio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El domingo se jugaron los partidos de ida de las semifinales del torneo oficial de divisiones inferiores. Se disputaron en cancha de Porte\u00f1o y Barracas, respectivamente. Los resultados fueron los siguientes: Sub\/11&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,3],"tags":[],"class_list":["post-2881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-general"],"_links":{"self":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2881"}],"version-history":[{"count":1,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2881\/revisions"}],"predecessor-version":[{"id":2883,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2881\/revisions\/2883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media\/2882"}],"wp:attachment":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}