{"id":2806,"date":"2024-07-26T18:24:43","date_gmt":"2024-07-26T21:24:43","guid":{"rendered":"https:\/\/emisoracolon.com.ar\/?p=2806"},"modified":"2024-07-26T18:24:43","modified_gmt":"2024-07-26T21:24:43","slug":"nuevo-piso-para-el-parroquial","status":"publish","type":"post","link":"https:\/\/emisoracolon.com.ar\/index.php\/2024\/07\/26\/nuevo-piso-para-el-parroquial\/","title":{"rendered":"Nuevo piso para el Parroquial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se comenz\u00f3 con la colocaci\u00f3n del nuevo piso en el gimnasio parroquial. En los \u00faltimos d\u00edas integrantes de la comisi\u00f3n directiva y las subcomisiones de v\u00f3ley y b\u00e1squet del Club Alianza se abocaron a la labor de colocar el piso en el sal\u00f3n ubicado en las calles 51 y 16.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recordemos que a comienzos de este a\u00f1o, la instituci\u00f3n junto al Instituto Monse\u00f1or de Andrea hab\u00eda iniciado una campa\u00f1a para recaudar fondos a trav\u00e9s de donaciones de metros de pisos de PVC, con el objetivo de mejorar el piso para las distintas disciplinas que se practican en el club. Desde hace tiempo el gimnasio es rentado por el Club Alianza para la disputa y entrenamiento de diversas actividades deportivas y ahora han sido impulsores de esta mejora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el gimnasio se desarrollan actividades deportivas, obviamente es utilizado por la escuela para su trabajo y por su espacio suelen desarrollarse espect\u00e1culos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se comenz\u00f3 con la colocaci\u00f3n del nuevo piso en el gimnasio parroquial. En los \u00faltimos d\u00edas integrantes de la comisi\u00f3n directiva y las subcomisiones de v\u00f3ley y b\u00e1squet del Club Alianza se&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,3],"tags":[],"class_list":["post-2806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-general"],"_links":{"self":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2806"}],"version-history":[{"count":1,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2806\/revisions"}],"predecessor-version":[{"id":2808,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2806\/revisions\/2808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media\/2807"}],"wp:attachment":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}