{"id":10903,"date":"2026-05-29T17:26:54","date_gmt":"2026-05-29T20:26:54","guid":{"rendered":"https:\/\/emisoracolon.com.ar\/?p=10903"},"modified":"2026-05-29T17:26:54","modified_gmt":"2026-05-29T20:26:54","slug":"dia-del-murguero","status":"publish","type":"post","link":"https:\/\/emisoracolon.com.ar\/index.php\/2026\/05\/29\/dia-del-murguero\/","title":{"rendered":"D\u00eda del murguero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Celebrar\u00e1n el D\u00eda del Murguero con m\u00fasica, danza y espect\u00e1culos en Plaza San Mart\u00edn<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este domingo se llevar\u00e1 a cabo la celebraci\u00f3n por el D\u00eda del Murguero en el Centro C\u00edvico \u2013 Plaza San Mart\u00edn, con una jornada abierta a toda la comunidad que reunir\u00e1 m\u00fasica en vivo, danza, batucada y distintas expresiones de la cultura popular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propuesta busca generar un espacio de encuentro y celebraci\u00f3n del esp\u00edritu carnavalero, con la participaci\u00f3n de artistas locales y regionales que ofrecer\u00e1n diferentes espect\u00e1culos a lo largo de la jornada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los artistas confirmados se encuentran Ver\u00e1 Juampi Ver\u00e1, School Dance, Aram\u00ed Romero con danza \u00e1rabe, Colonba, Los Pampas, Pablo Van Becelaere, la Murga \u201cDel Tonto\u201d, Cecilia Rodr\u00edguez, Danilo D\u00edaz, Corre Lola e Inigualable Che.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la organizaci\u00f3n destacaron que ser\u00e1 una oportunidad para compartir en familia y disfrutar de una tarde cargada de ritmo, color y alegr\u00eda popular, reivindicando el valor cultural de l<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Celebrar\u00e1n el D\u00eda del Murguero con m\u00fasica, danza y espect\u00e1culos en Plaza San Mart\u00edn Este domingo se llevar\u00e1 a cabo la celebraci\u00f3n por el D\u00eda del Murguero en el Centro C\u00edvico \u2013&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10903"}],"version-history":[{"count":1,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10903\/revisions"}],"predecessor-version":[{"id":10905,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10903\/revisions\/10905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10904"}],"wp:attachment":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}