{"id":10875,"date":"2026-05-27T16:28:43","date_gmt":"2026-05-27T19:28:43","guid":{"rendered":"https:\/\/emisoracolon.com.ar\/?p=10875"},"modified":"2026-05-27T16:28:43","modified_gmt":"2026-05-27T19:28:43","slug":"lisandro-kelly-la-crisis-economica-y-el-impacto-en-la-vida-cotidiana","status":"publish","type":"post","link":"https:\/\/emisoracolon.com.ar\/index.php\/2026\/05\/27\/lisandro-kelly-la-crisis-economica-y-el-impacto-en-la-vida-cotidiana\/","title":{"rendered":"Lisandro Kelly La crisis econ\u00f3mica y el impacto en la vida cotidiana\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El pr\u00f3ximo viernes a las 18.30, en el sal\u00f3n de la UOM ubicado en calle 13 entre 46 y 47, se realizar\u00e1 una charla debate titulada \u201cLa crisis econ\u00f3mica y el impacto en la vida cotidiana\u201d, organizada por el grupo Proyecto Pichoniano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propuesta tendr\u00e1 como principal expositor a Lisandro Kelly, psic\u00f3logo social, licenciado en Ciencias Econ\u00f3micas, docente de la Universidad Nacional de Rosario e integrante del \u00e1rea de investigaciones econ\u00f3micas y financieras de esa casa de estudios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la organizaci\u00f3n, Silvia Sabetta explic\u00f3 que el objetivo es abrir espacios de reflexi\u00f3n colectiva sobre situaciones cotidianas que impactan en la salud mental y en la subjetividad de las personas. \u201cQueremos darle continuidad a una serie de encuentros abiertos, tipo taller y debate, sobre temas que nos atraviesan como sociedad\u201d, se\u00f1al\u00f3, recordando adem\u00e1s la buena repercusi\u00f3n que tuvo una actividad similar realizada meses atr\u00e1s en el Sindicato de la Carne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la entrevista, Lisandro Kelly analiz\u00f3 las consecuencias sociales y humanas de la crisis econ\u00f3mica actual, se\u00f1alando que uno de los primeros impactos aparece en las dificultades para llegar a fin de mes y en el deterioro de la calidad de vida. Explic\u00f3 adem\u00e1s que las crisis no afectan a todos de la misma manera y remarc\u00f3 que los j\u00f3venes y los adultos mayores suelen ser de los sectores m\u00e1s golpeados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kelly describi\u00f3 c\u00f3mo el sobretrabajo, el pluriempleo y la incertidumbre modifican la din\u00e1mica familiar y comunitaria, reduciendo tiempos de encuentro y aumentando situaciones de estr\u00e9s, angustia y aislamiento. Tambi\u00e9n sostuvo que los procesos de crisis prolongados favorecen el individualismo y la fragmentaci\u00f3n social, aunque destac\u00f3 que hist\u00f3ricamente las salidas m\u00e1s saludables surgieron desde la solidaridad, la cooperaci\u00f3n y el trabajo colectivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, uno de los ejes centrales de la charla ser\u00e1 precisamente el concepto de \u201cPensar juntos para transformar lo que nos atraviesa\u201d, una consigna que, seg\u00fan los organizadores, apunta a recuperar los v\u00ednculos sociales y construir respuestas colectivas frente a la crisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa idea es salir de la queja individual para pensar y hacer con otros\u201d, expres\u00f3 Silvia Sabetta, quien remarc\u00f3 la importancia de fortalecer espacios comunitarios, clubes, instituciones y redes de acompa\u00f1amiento social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Kelly sostuvo que \u201cla batalla que se pierde es la batalla que se abandona\u201d y plante\u00f3 la necesidad de \u201cplanificar la esperanza\u201d en medio de un contexto dif\u00edcil. \u201cLas transformaciones reales siempre son con otros, nunca en soledad\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad ser\u00e1 abierta a toda la comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo viernes a las 18.30, en el sal\u00f3n de la UOM ubicado en calle 13 entre 46 y 47, se realizar\u00e1 una charla debate titulada \u201cLa crisis econ\u00f3mica y el impacto&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10875"}],"version-history":[{"count":1,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10875\/revisions"}],"predecessor-version":[{"id":10876,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10875\/revisions\/10876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10822"}],"wp:attachment":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}