{"id":10819,"date":"2026-05-21T17:14:54","date_gmt":"2026-05-21T20:14:54","guid":{"rendered":"https:\/\/emisoracolon.com.ar\/?p=10819"},"modified":"2026-05-21T17:14:54","modified_gmt":"2026-05-21T20:14:54","slug":"diputados-aprobo-hacer-caer-el-descuento-por-zona-fria","status":"publish","type":"post","link":"https:\/\/emisoracolon.com.ar\/index.php\/2026\/05\/21\/diputados-aprobo-hacer-caer-el-descuento-por-zona-fria\/","title":{"rendered":"Diputados aprob\u00f3 hacer caer el descuento por Zona Fr\u00eda."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fernanda D\u00edaz rechaz\u00f3 la modificaci\u00f3n del R\u00e9gimen de Zona Fr\u00eda y advirti\u00f3 por el impacto en 6.455 hogares de Col\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada nacional Fernanda D\u00edaz intervino este mi\u00e9rcoles en la sesi\u00f3n especial de la C\u00e1mara de Diputados de la Naci\u00f3n Argentina para rechazar la modificaci\u00f3n del R\u00e9gimen de Zona Fr\u00eda impulsada por el gobierno de Javier Milei, iniciativa que deroga la ampliaci\u00f3n implementada en 2021 y elimina descuentos de hasta el 50% en las tarifas de gas para millones de usuarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan expres\u00f3 la legisladora colonense, la medida afectar\u00e1 a m\u00e1s de 4 millones de argentinos y argentinas, entre ellos 6.455 hogares de Col\u00f3n que actualmente acceden al beneficio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00edaz fue una de las 18 diputadas y diputados del bloque Uni\u00f3n por la Patria que tom\u00f3 la palabra durante el debate para advertir sobre las consecuencias sociales de la modificaci\u00f3n. En ese marco, cuestion\u00f3 que el oficialismo avanzara contra el beneficio destinado a las familias mientras, en la misma sesi\u00f3n, se trataba una condonaci\u00f3n de deuda de 1.800 millones de d\u00f3lares para empresas energ\u00e9ticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su exposici\u00f3n, la diputada sostuvo que el impacto econ\u00f3mico de perder el descuento en las facturas de gas tendr\u00e1 consecuencias directas en la econom\u00eda cotidiana de miles de familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste beneficio representa, hoy en d\u00eda, (con datos del consumo de verano) entre 7 y 10 litros de leche, 8 paquetes de yerba, de 10 a 12 kilos de az\u00facar, un paquete de 25 pa\u00f1ales, 3 o 4 kilos de carne picada, o los medicamentos que le sacaron a los jubilados del PAMI. Con esta nueva estafa de La Libertad Avanza, los vecinos de nuestras ciudades van a tener que decidir entre pagar la factura del gas o cumplir con una comida m\u00e1s diaria\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En contraste, el diputado colonense Pablo Ansaloni, alineado actualmente con La Libertad Avanza, vot\u00f3 a favor de la iniciativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al cierre de su intervenci\u00f3n, D\u00edaz remarc\u00f3 que el debate sobre la Zona Fr\u00eda excede lo tarifario y pone en discusi\u00f3n el rol del Estado frente a los servicios p\u00fablicos esenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDiscutir hoy esta modificaci\u00f3n de la zona fr\u00eda es discutir qu\u00e9 pa\u00eds queremos construir, es discutir si el acceso a un servicio p\u00fablico esencial, como es el gas, es un derecho b\u00e1sico o queda librado al azar a ver si es rentable o no para el empresariado. El Estado no puede ser un mero observador de esta situaci\u00f3n\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fernanda D\u00edaz rechaz\u00f3 la modificaci\u00f3n del R\u00e9gimen de Zona Fr\u00eda y advirti\u00f3 por el impacto en 6.455 hogares de Col\u00f3n La diputada nacional Fernanda D\u00edaz intervino este mi\u00e9rcoles en la sesi\u00f3n especial&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10819"}],"version-history":[{"count":1,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10819\/revisions"}],"predecessor-version":[{"id":10820,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10819\/revisions\/10820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media\/9704"}],"wp:attachment":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}