{"id":10733,"date":"2026-05-13T16:14:20","date_gmt":"2026-05-13T19:14:20","guid":{"rendered":"https:\/\/emisoracolon.com.ar\/?p=10733"},"modified":"2026-05-13T16:14:20","modified_gmt":"2026-05-13T19:14:20","slug":"nicolas-lujan-los-espacios-con-justicia-social","status":"publish","type":"post","link":"https:\/\/emisoracolon.com.ar\/index.php\/2026\/05\/13\/nicolas-lujan-los-espacios-con-justicia-social\/","title":{"rendered":"Nicol\u00e1s Luj\u00e1n \u201clos espacios con Justicia Social\u201d"},"content":{"rendered":"\n<p>Nicol\u00e1s Luj\u00e1n inform\u00f3 que, por cuestiones clim\u00e1ticas, fue postergada para el pr\u00f3ximo s\u00e1bado la inauguraci\u00f3n del Centro Socio Comunitario que funcionar\u00e1 en un predio cedido por la Comisi\u00f3n de Apoyo a Menores en la Familia a la Municipalidad de Col\u00f3n. Destac\u00f3 que el espacio busca generar \u201cjusticia social\u201d, promover la cultura del trabajo y brindar contenci\u00f3n para que \u201clos pibes no est\u00e9n en la calle\u201d. En ese marco, valor\u00f3 el rol de las instituciones locales y remarc\u00f3 que \u201ccuando el Estado no se corre y trabaja mancomunadamente con las instituciones, suceden este tipo de proyectos\u201d. Adem\u00e1s, salud\u00f3 a la comunidad de la Casa de las Infancias y reconoci\u00f3 la tarea de exdirectoras y plante\u00f3 la necesidad de conformar una cooperadora que acompa\u00f1e el trabajo de la instituci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicol\u00e1s Luj\u00e1n inform\u00f3 que, por cuestiones clim\u00e1ticas, fue postergada para el pr\u00f3ximo s\u00e1bado la inauguraci\u00f3n del Centro Socio Comunitario que funcionar\u00e1 en un predio cedido por la Comisi\u00f3n de Apoyo a Menores&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10733"}],"version-history":[{"count":1,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10733\/revisions"}],"predecessor-version":[{"id":10734,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10733\/revisions\/10734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10729"}],"wp:attachment":[{"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisoracolon.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}